{"id":720,"date":"2018-05-05T18:31:14","date_gmt":"2018-05-05T18:31:14","guid":{"rendered":"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/?p=720"},"modified":"2018-05-27T23:50:56","modified_gmt":"2018-05-27T23:50:56","slug":"chp-e-internews-desarrollan-taller-de-periodismo-digital-en-comayagua","status":"publish","type":"post","link":"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/2018\/05\/05\/chp-e-internews-desarrollan-taller-de-periodismo-digital-en-comayagua\/","title":{"rendered":"CHP e Internews desarrollan taller de periodismo digital en Comayagua"},"content":{"rendered":"<p><strong><em>Comayagua. <\/em><\/strong>El Colegio de Periodistas de Honduras (CPH) con el apoyo de Internews, inaugur\u00f3 hoy el taller de Periodismo Digital \u201cNuevas Tendencias Digitales del Periodismo\u201d con la participaci\u00f3n de 15 profesionales de la comunicaci\u00f3n de la zona central del pa\u00eds.<\/p>\n<p>El taller se celebrar\u00e1 desde el 5 de mayo hasta el 6 de mayo con una duraci\u00f3n de 15 horas, tiempo durante el que los participantes potenciar\u00e1n sus capacidades en el manejo de Sistemas de Manejo de Contenido web (CMS, por sus siglas en ingl\u00e9s) con especial \u00e9nfasis en la plataforma WordPress.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-721\" src=\"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-content\/uploads\/2018\/05\/Periodistas-Comayagua-300x169.jpg\" alt=\"\" width=\"369\" height=\"208\" srcset=\"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-content\/uploads\/2018\/05\/Periodistas-Comayagua-300x169.jpg 300w, http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-content\/uploads\/2018\/05\/Periodistas-Comayagua.jpg 500w\" sizes=\"auto, (max-width: 369px) 100vw, 369px\" \/><\/p>\n<p>Este taller es parte una programaci\u00f3n de capacitaciones elaborada por la Junta Directiva del CPH, presidida por Dagoberto Rodr\u00edguez, y que aspira a potenciar las habilidades de los periodistas en todo el pa\u00eds a trav\u00e9s de la actualizaci\u00f3n del conocimiento y nuevas tendencias comunicacionales.<\/p>\n<p>Hasta el momento el CPH ha capacitado, con la colaboraci\u00f3n de Internews, a m\u00e1s de cien periodistas de todo el pa\u00eds. El CPH e Internews han otorgado becas a todos esos profesionales de la comunicaci\u00f3n.<\/p>\n<p>Rodr\u00edguez anunci\u00f3 que ya tienen lista la convocatoria para una capacitaci\u00f3n en Choluteca. Tambi\u00e9n hay planes de ofrecer nuevas capacitaciones en San Pedro Sula, La Ceiba y Tegucigalpa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comayagua. El Colegio de Periodistas de Honduras (CPH) con el apoyo de Internews, inaugur\u00f3 hoy el taller de Periodismo Digital \u201cNuevas Tendencias Digitales del Periodismo\u201d con la participaci\u00f3n de 15 profesionales de la comunicaci\u00f3n de la zona central del pa\u00eds. El taller se celebrar\u00e1 desde el 5 de mayo hasta el 6 de mayo con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[19,143,23,18,132,26],"class_list":["post-720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-gremial","tag-colegio-de-periodistas-honduras","tag-comayagua","tag-dagoberto-rodriguez","tag-honduras","tag-periodismo-honduras","tag-periodistas-honduras"],"_links":{"self":[{"href":"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-json\/wp\/v2\/posts\/720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-json\/wp\/v2\/comments?post=720"}],"version-history":[{"count":4,"href":"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-json\/wp\/v2\/posts\/720\/revisions"}],"predecessor-version":[{"id":726,"href":"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-json\/wp\/v2\/posts\/720\/revisions\/726"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-json\/wp\/v2\/media\/722"}],"wp:attachment":[{"href":"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-json\/wp\/v2\/media?parent=720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-json\/wp\/v2\/categories?post=720"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/colegiodeperiodistasdehonduras.hn\/wp\/wp-json\/wp\/v2\/tags?post=720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}